{"id":64528,"date":"2024-05-23T16:54:48","date_gmt":"2024-05-23T13:54:48","guid":{"rendered":"https:\/\/www.promodel.fi\/?page_id=64528"},"modified":"2024-05-23T17:00:19","modified_gmt":"2024-05-23T14:00:19","slug":"become-a-model","status":"publish","type":"page","link":"https:\/\/www.promodel.fi\/en\/become-a-model\/","title":{"rendered":"Become a model"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-64528","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Become a model - Promodel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.promodel.fi\/en\/become-a-model\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Become a model - Promodel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.promodel.fi\/en\/become-a-model\/\" \/>\n<meta property=\"og:site_name\" content=\"Promodel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61563778105412\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T14:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.promodel.fi\/wp-content\/uploads\/2019\/11\/promodel-og.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.promodel.fi\\\/en\\\/become-a-model\\\/\",\"url\":\"https:\\\/\\\/www.promodel.fi\\\/en\\\/become-a-model\\\/\",\"name\":\"Become a model - Promodel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.promodel.fi\\\/#website\"},\"datePublished\":\"2024-05-23T13:54:48+00:00\",\"dateModified\":\"2024-05-23T14:00:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.promodel.fi\\\/en\\\/become-a-model\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.promodel.fi\\\/en\\\/become-a-model\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.promodel.fi\\\/en\\\/become-a-model\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/www.promodel.fi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Become a model\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.promodel.fi\\\/#website\",\"url\":\"https:\\\/\\\/www.promodel.fi\\\/\",\"name\":\"Promodel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.promodel.fi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.promodel.fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.promodel.fi\\\/#organization\",\"name\":\"Promodel Oy\",\"url\":\"https:\\\/\\\/www.promodel.fi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.promodel.fi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.promodel.fi\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/promodel-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.promodel.fi\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/promodel-logo.png\",\"width\":1000,\"height\":307,\"caption\":\"Promodel Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.promodel.fi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61563778105412\",\"https:\\\/\\\/www.instagram.com\\\/promodel_model_management\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Become a model - Promodel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.promodel.fi\/en\/become-a-model\/","og_locale":"en_US","og_type":"article","og_title":"Become a model - Promodel","og_url":"https:\/\/www.promodel.fi\/en\/become-a-model\/","og_site_name":"Promodel","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61563778105412","article_modified_time":"2024-05-23T14:00:19+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.promodel.fi\/wp-content\/uploads\/2019\/11\/promodel-og.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.promodel.fi\/en\/become-a-model\/","url":"https:\/\/www.promodel.fi\/en\/become-a-model\/","name":"Become a model - Promodel","isPartOf":{"@id":"https:\/\/www.promodel.fi\/#website"},"datePublished":"2024-05-23T13:54:48+00:00","dateModified":"2024-05-23T14:00:19+00:00","breadcrumb":{"@id":"https:\/\/www.promodel.fi\/en\/become-a-model\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.promodel.fi\/en\/become-a-model\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.promodel.fi\/en\/become-a-model\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/www.promodel.fi\/en\/"},{"@type":"ListItem","position":2,"name":"Become a model"}]},{"@type":"WebSite","@id":"https:\/\/www.promodel.fi\/#website","url":"https:\/\/www.promodel.fi\/","name":"Promodel","description":"","publisher":{"@id":"https:\/\/www.promodel.fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.promodel.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.promodel.fi\/#organization","name":"Promodel Oy","url":"https:\/\/www.promodel.fi\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.promodel.fi\/#\/schema\/logo\/image\/","url":"https:\/\/www.promodel.fi\/wp-content\/uploads\/2019\/09\/promodel-logo.png","contentUrl":"https:\/\/www.promodel.fi\/wp-content\/uploads\/2019\/09\/promodel-logo.png","width":1000,"height":307,"caption":"Promodel Oy"},"image":{"@id":"https:\/\/www.promodel.fi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61563778105412","https:\/\/www.instagram.com\/promodel_model_management\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.promodel.fi\/en\/wp-json\/wp\/v2\/pages\/64528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.promodel.fi\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.promodel.fi\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.promodel.fi\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.promodel.fi\/en\/wp-json\/wp\/v2\/comments?post=64528"}],"version-history":[{"count":1,"href":"https:\/\/www.promodel.fi\/en\/wp-json\/wp\/v2\/pages\/64528\/revisions"}],"predecessor-version":[{"id":64529,"href":"https:\/\/www.promodel.fi\/en\/wp-json\/wp\/v2\/pages\/64528\/revisions\/64529"}],"wp:attachment":[{"href":"https:\/\/www.promodel.fi\/en\/wp-json\/wp\/v2\/media?parent=64528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}